{"id":31526,"date":"2025-03-15T08:44:59","date_gmt":"2025-03-15T12:44:59","guid":{"rendered":"https:\/\/pmbiaquebec.ca\/?page_id=31526"},"modified":"2026-08-29T08:15:42","modified_gmt":"2026-08-29T12:15:42","slug":"pmbia-quebec-niveau-2-certification","status":"publish","type":"page","link":"https:\/\/pmbiaquebec.ca\/fr\/pmbia-quebec-niveau-2-certification\/","title":{"rendered":"PMBIA QUEBEC &#8211; NIVEAU 2 CERTIFICATION"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"31526\" class=\"elementor elementor-31526\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-476addb e-flex e-con-boxed e-con e-parent\" data-id=\"476addb\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-bcbacf5 e-con-full e-flex e-con e-child\" data-id=\"bcbacf5\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-60ba6a9e elementor-widget elementor-widget-heading\" data-id=\"60ba6a9e\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">AM\u00c9LIORE TON PILOTAGE<br>\nPARTAGE TA PASSION<br>\nDEVIENT UN ENTRAINEUR PMBIA D\u00c8S AUJOURD'HUI!<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-62f416ab elementor-widget elementor-widget-text-editor\" data-id=\"62f416ab\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tLEADER EN NORMES DE CERTIFICATIONS DE L'INDUSTRIE DU V\u00c9LO DE MONTAGNE\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ce205ca e-con-full e-flex e-con e-child\" data-id=\"ce205ca\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-68dc4bb elementor-widget elementor-widget-image\" data-id=\"68dc4bb\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/pmbiaquebec.ca\/wp-content\/uploads\/2025\/02\/Screenshot-2025-02-19-at-08.03.04-150x150.png\" class=\"attachment-thumbnail size-thumbnail wp-image-30148\" alt=\"\" srcset=\"https:\/\/pmbiaquebec.ca\/wp-content\/uploads\/2025\/02\/Screenshot-2025-02-19-at-08.03.04-150x150.png 150w, https:\/\/pmbiaquebec.ca\/wp-content\/uploads\/2025\/02\/Screenshot-2025-02-19-at-08.03.04-13x12.png 13w, https:\/\/pmbiaquebec.ca\/wp-content\/uploads\/2025\/02\/Screenshot-2025-02-19-at-08.03.04-590x590.png 590w, https:\/\/pmbiaquebec.ca\/wp-content\/uploads\/2025\/02\/Screenshot-2025-02-19-at-08.03.04-200x200.png 200w, https:\/\/pmbiaquebec.ca\/wp-content\/uploads\/2025\/02\/Screenshot-2025-02-19-at-08.03.04-300x300.png 300w, https:\/\/pmbiaquebec.ca\/wp-content\/uploads\/2025\/02\/Screenshot-2025-02-19-at-08.03.04-100x100.png 100w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a8a242e e-grid e-con-boxed e-con e-parent\" data-id=\"a8a242e\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-19d7916 e-con-full e-flex e-con e-child\" data-id=\"19d7916\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-63088fc6 e-con-full e-flex e-con e-child\" data-id=\"63088fc6\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5d1c6b8d elementor-widget elementor-widget-heading\" data-id=\"5d1c6b8d\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Niveau II et III : Programmes de certification pour instructeur\n<br>\u00c9levez votre coaching!<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-142b03a0 elementor-widget elementor-widget-text-editor\" data-id=\"142b03a0\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Perfectionnez votre enseignement avec le cours complet Niveau II AIR et TECH ! Formations de 4 jours pour am\u00e9liorer vos comp\u00e9tences en pilotage et en enseignement au-del\u00e0 du Niveau 1.<br>\n<br>La certification TECH d\u00e9veloppe les comp\u00e9tences en sentiers naturels (enduro); mont\u00e9e et descentes techniques, virages naturels et manoeuvres avanc\u00e9s.<br>\n<br>La certification AIR d\u00e9veloppe les comp\u00e9tences en terrain \"flow\".  Descentes techniques, virages sur\u00e9lev\u00e9s, et manoeuvres de sauts et drops.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5f7c86e7 e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"5f7c86e7\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeInRight&quot;}\">\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c006426 e-flex e-con-boxed e-con e-parent\" data-id=\"c006426\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8d5c54c elementor-widget elementor-widget-heading\" data-id=\"8d5c54c\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Stages PMBIA Niveau 2 et 3<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-49761af e-grid elementor-hidden-mobile e-con-boxed e-con e-parent\" data-id=\"49761af\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-aced254 elementor-widget elementor-widget-heading\" data-id=\"aced254\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Stage<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-27838ff elementor-widget elementor-widget-heading\" data-id=\"27838ff\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Site de pratique<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-370962c elementor-widget elementor-widget-heading\" data-id=\"370962c\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Date de d\u00e9but<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7b6cd4d elementor-widget elementor-widget-heading\" data-id=\"7b6cd4d\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Date de fin<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7b183c6 elementor-widget elementor-widget-heading\" data-id=\"7b183c6\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Statut<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c312958 elementor-widget elementor-widget-heading\" data-id=\"c312958\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Prix<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1d85414 elementor-widget elementor-widget-heading\" data-id=\"1d85414\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">S'inscrire<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-94502c2 e-grid e-con-boxed e-con e-parent\" data-id=\"94502c2\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-57b3dc9 elementor-widget elementor-widget-heading\" data-id=\"57b3dc9\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Niveau 2 Tech<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b0a3ac4 elementor-widget elementor-widget-heading\" data-id=\"b0a3ac4\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Belle-Neige<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-15a4694 elementor-widget elementor-widget-heading\" data-id=\"15a4694\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">18-09-2026<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a893ab6 elementor-widget elementor-widget-heading\" data-id=\"a893ab6\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">21-09-2026<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1121ece elementor-align-center elementor-widget elementor-widget-button\" data-id=\"1121ece\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/pmbiaquebec.ca\/fr\/listing\/pmbia-niveau-2-tech-belle-neige-18-au-21-septembre-2026\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Disponible<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-41b72a8 elementor-widget elementor-widget-heading\" data-id=\"41b72a8\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">749$<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-da74fba elementor-align-center elementor-widget elementor-widget-button\" data-id=\"da74fba\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/pmbiaquebec.ca\/fr\/listing\/pmbia-niveau-2-tech-belle-neige-18-au-21-septembre-2026\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">S'inscrire<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-eb82539 e-grid e-con-boxed e-con e-parent\" data-id=\"eb82539\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ccf2824 elementor-widget elementor-widget-heading\" data-id=\"ccf2824\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Niveau 2 Air<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1eb9ad7 elementor-widget elementor-widget-heading\" data-id=\"1eb9ad7\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Bromont<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9cc52ed elementor-widget elementor-widget-heading\" data-id=\"9cc52ed\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">26-09-2026<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9c67963 elementor-widget elementor-widget-heading\" data-id=\"9c67963\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">29-09-2026<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0152e5f elementor-align-center elementor-widget elementor-widget-button\" data-id=\"0152e5f\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/pmbiaquebec.ca\/fr\/listing\/pmbia-niveau-2-air-bromont-24-au-27-septembre-2026\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Disponible<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5b6a240 elementor-widget elementor-widget-heading\" data-id=\"5b6a240\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">749$<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fb79473 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"fb79473\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/pmbiaquebec.ca\/fr\/listing\/pmbia-niveau-2-air-bromont-24-au-27-septembre-2026\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">S'inscrire<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-72a7cb1 e-grid e-con-boxed e-con e-parent\" data-id=\"72a7cb1\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3ffe545 elementor-widget elementor-widget-heading\" data-id=\"3ffe545\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Niveau 2 Tech<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-53a4b8f elementor-widget elementor-widget-heading\" data-id=\"53a4b8f\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Sentiers du Moulin<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3561243 elementor-widget elementor-widget-heading\" data-id=\"3561243\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">8-10-2026<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3086bf5 elementor-widget elementor-widget-heading\" data-id=\"3086bf5\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">11-10-2026<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-372d448 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"372d448\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/pmbiaquebec.ca\/fr\/listing\/pmbia-niveau-2-tech-sentiers-du-moulin-8-au-11-septembre-2026\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Disponible<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9f2ac6b elementor-widget elementor-widget-heading\" data-id=\"9f2ac6b\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">749$<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-55a4961 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"55a4961\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/pmbiaquebec.ca\/fr\/listing\/pmbia-niveau-2-tech-sentiers-du-moulin-8-au-11-septembre-2026\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">S'inscrire<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-20fc9016 e-flex e-con-boxed e-con e-parent\" data-id=\"20fc9016\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1eb856d4 elementor-widget elementor-widget-heading\" data-id=\"1eb856d4\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Liste d'attente<br>Demande de stage<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-58ed1be8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"58ed1be8\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-34e9f1e5\" data-id=\"34e9f1e5\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6eb66d23 elementor-button-align-center elementor-widget elementor-widget-form\" data-id=\"6eb66d23\" data-element_type=\"widget\" data-settings=\"{&quot;step_next_label&quot;:&quot;Next&quot;,&quot;step_previous_label&quot;:&quot;Previous&quot;,&quot;button_width&quot;:&quot;100&quot;,&quot;step_type&quot;:&quot;number_text&quot;,&quot;step_icon_shape&quot;:&quot;circle&quot;}\" data-widget_type=\"form.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<form class=\"elementor-form\" method=\"post\" name=\"New Form\" action=\"\">\n\t\t\t<input type=\"hidden\" name=\"post_id\" value=\"31526\"\/>\n\t\t\t<input type=\"hidden\" name=\"form_id\" value=\"6eb66d23\"\/>\n\t\t\t<input type=\"hidden\" name=\"referer_title\" value=\"PMBIA Qu\u00e9bec\" \/>\n\n\t\t\t\n\t\t\t<div class=\"elementor-form-fields-wrapper elementor-labels-above\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-name elementor-col-50\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-name\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tNom\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[name]\" id=\"form-field-name\" class=\"elementor-field elementor-size-md  elementor-field-textual\" placeholder=\"Nom\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-field_3b7b280 elementor-col-50\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-field_3b7b280\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tVille\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[field_3b7b280]\" id=\"form-field-field_3b7b280\" class=\"elementor-field elementor-size-md  elementor-field-textual\" placeholder=\"Ville\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-email elementor-field-group elementor-column elementor-field-group-email elementor-col-50 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-email\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tCourriel\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"email\" name=\"form_fields[email]\" id=\"form-field-email\" class=\"elementor-field elementor-size-md  elementor-field-textual\" placeholder=\"Courriel\" required=\"required\" aria-required=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-field_8d3ffd8 elementor-col-50 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-field_8d3ffd8\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tNum\u00e9ro de t\u00e9l\u00e9phone\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[field_8d3ffd8]\" id=\"form-field-field_8d3ffd8\" class=\"elementor-field elementor-size-md  elementor-field-textual\" placeholder=\"Num\u00e9ro de t\u00e9l\u00e9phone\" required=\"required\" aria-required=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-field_c67f9c4 elementor-col-50 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-field_c67f9c4\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tLieu d\u00e9sir\u00e9\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[field_c67f9c4]\" id=\"form-field-field_c67f9c4\" class=\"elementor-field elementor-size-md  elementor-field-textual\" placeholder=\"Endroits o\u00f9 vous pouvez vous d\u00e9placer\" required=\"required\" aria-required=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-field_beb26e9 elementor-col-50 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-field_beb26e9\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tNombre approximatif de participants\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[field_beb26e9]\" id=\"form-field-field_beb26e9\" class=\"elementor-field elementor-size-md  elementor-field-textual\" placeholder=\"Participants\" required=\"required\" aria-required=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-group elementor-column elementor-field-type-submit elementor-col-100 e-form__buttons\">\n\t\t\t\t\t<button type=\"submit\" class=\"elementor-button elementor-size-lg elementor-animation-pulse-grow\">\n\t\t\t\t\t\t<span >\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Envoyer<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/button>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<input type=\"hidden\" name=\"trp-form-language\" value=\"fr\"\/><\/form>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-f70ab8e e-flex e-con-boxed e-con e-parent\" data-id=\"f70ab8e\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-ef5be2f e-grid e-con-full e-con e-child\" data-id=\"ef5be2f\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-d8495b3 e-con-full e-flex e-con e-child\" data-id=\"d8495b3\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-20ef162 e-con-full e-flex e-con e-child\" data-id=\"20ef162\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-635e533 elementor-widget elementor-widget-heading\" data-id=\"635e533\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Je veux coacher les sauts et drops<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-05354e8 elementor-widget elementor-widget-heading\" data-id=\"05354e8\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Niveau II \/ III<br>\nAir (4 jours)<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-08bacce elementor-widget elementor-widget-heading\" data-id=\"08bacce\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><i>Certification coaching a\u00e9rien<\/i><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9150c8c e-con-full e-flex e-con e-child\" data-id=\"9150c8c\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-ddca39f e-con-full e-flex e-con e-child\" data-id=\"ddca39f\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2eb60ac elementor-widget elementor-widget-heading\" data-id=\"2eb60ac\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Je veux coacher du pilotage technique<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4a1d9b7 elementor-widget elementor-widget-heading\" data-id=\"4a1d9b7\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Niveau II \/ III<br>\nTech (4 jours)<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-05d3cfa elementor-widget elementor-widget-heading\" data-id=\"05d3cfa\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><i>Certification coaching technique<\/i><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3d20e1c e-con-full e-flex e-con e-child\" data-id=\"3d20e1c\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-a28c151 e-grid e-con-full e-con e-child\" data-id=\"a28c151\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-beecbd9 elementor-widget elementor-widget-n-accordion\" data-id=\"beecbd9\" data-element_type=\"widget\" data-settings=\"{&quot;default_state&quot;:&quot;all_collapsed&quot;,&quot;max_items_expended&quot;:&quot;one&quot;,&quot;n_accordion_animation_duration&quot;:{&quot;unit&quot;:&quot;ms&quot;,&quot;size&quot;:400,&quot;sizes&quot;:[]}}\" data-widget_type=\"nested-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"e-n-accordion\" aria-label=\"Survol du Ride Guide\">\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-2000\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"1\" tabindex=\"0\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-2000\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Ce que vous apprendrez - Niveau 2 AIR <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><i aria-hidden=\"true\" class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t<span class='e-closed'><i aria-hidden=\"true\" class=\"fas fa-plus\"><\/i><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-2000\" class=\"elementor-element elementor-element-067eaa3 e-con-full e-flex e-con e-child\" data-id=\"067eaa3\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-94e7b05 elementor-widget elementor-widget-text-editor\" data-id=\"94e7b05\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La certification d'instructeur PMBIA Niveau 2\/3 \u2013 AIR forme les instructeurs \u00e0 enseigner des habilet\u00e9s interm\u00e9diaires et avanc\u00e9s sur des sentiers progression de type <i>flow<\/i>. Le cours met l'accent sur le perfectionnement des comp\u00e9tences en virages, en saut et en drops, et en pilotage technique sur pistes bleus, noirs et certaines double noirs.<\/p>\n<ul>\n<li>Enseignez \u00e0 des riders interm\u00e9diaires \u00e0 avanc\u00e9s sur des terrains techniques et de type flow en bike park.<\/li>\n<li>Perfectionnez vos habilet\u00e9s en virages, descentes, pentes raides, rock rolls, pompage et man\u0153uvres techniques.<\/li>\n<li>Initiez s\u00e9curitairement vos \u00e9l\u00e8ves aux sauts de type table et aux drops de petite \u00e0 moyenne taille.<\/li>\n<li>Am\u00e9liorez votre gestion des risques, votre encadrement et vos habilet\u00e9s relationnelles \u00e0 plus haute vitesse.<\/li>\n<li>Utilisez les mod\u00e8les et m\u00e9thodologies PMBIA pour structurer des cours efficaces.<\/li>\n<li>Recevez du mentorat, pratiquez l\u2019enseignement et obtenez des retours quotidiens d\u2019un formateur PMBIA.<\/li>\n<\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-2001\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"2\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-2001\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> \u00c0 qui s\u2019adresse ce cours <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><i aria-hidden=\"true\" class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t<span class='e-closed'><i aria-hidden=\"true\" class=\"fas fa-plus\"><\/i><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-2001\" class=\"elementor-element elementor-element-12ca9d0 e-con-full e-flex e-con e-child\" data-id=\"12ca9d0\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e4929ac elementor-widget elementor-widget-text-editor\" data-id=\"e4929ac\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Con\u00e7u pour les instructeurs certifi\u00e9s PMBIA souhaitant enseigner aux riders interm\u00e9diaires \u00e0 avanc\u00e9s sur des terrains techniques et de type jump\/flow.<\/p>\n            <ul>\n                <li>Id\u00e9ale pour les \u00e9coles de v\u00e9lo, les clubs et les services de coaching.<\/li>\n                <li>Sur des sentiers verts, bleus et noirs, y compris les pistes de sauts et de flow en bike park<\/li>\n                <li>Des le\u00e7ons ax\u00e9es sur les virages relev\u00e9s et \u00e0 plat, les descentes, les pentes raides, les passages rocheux, le pumping et l\u2019introduction aux sauts et drops<\/li>\n                <li>G\u00e9n\u00e9ralement offert dans des bike parks avec remont\u00e9e m\u00e9canique ou des centres de trail.<\/li>\n                <li>Dans des sites situ\u00e9s \u00e0 moins de 2 heures des soins m\u00e9dicaux d\u2019urgence<\/li>\n            <\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-2002\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"3\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-2002\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Pourquoi prendre ce cours? <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><i aria-hidden=\"true\" class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t<span class='e-closed'><i aria-hidden=\"true\" class=\"fas fa-plus\"><\/i><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-2002\" class=\"elementor-element elementor-element-69bf613 e-con-full e-flex e-con e-child\" data-id=\"69bf613\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-55da65b elementor-widget elementor-widget-text-editor\" data-id=\"55da65b\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t <ul>\n                <li>Obtenez votre certification pour enseigner sur des terrains avanc\u00e9s et ma\u00eetriser des techniques avanc\u00e9es.<\/li>\n                <li>Acqu\u00e9rez une exp\u00e9rience concr\u00e8te du coaching dans des situations r\u00e9elles.<\/li>\n                <li>Apprenez des m\u00e9thodes d\u2019enseignement structur\u00e9es et bas\u00e9es sur les habilet\u00e9s avec des formateurs exp\u00e9riment\u00e9s de la PMBIA.<\/li>\n                <li>Am\u00e9liorez votre gestion des risques et votre planification de cours pour le pilotage \u00e0 haute vitesse.<\/li>\n                <li>Faites progresser votre carri\u00e8re en enseignement du v\u00e9lo avec une certification reconnue dans l\u2019industrie.<\/li>\n            <\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-2003\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"4\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-2003\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Pr\u00e9-requis <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><i aria-hidden=\"true\" class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t<span class='e-closed'><i aria-hidden=\"true\" class=\"fas fa-plus\"><\/i><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-2003\" class=\"elementor-element elementor-element-9caff94 e-con-full e-flex e-con e-child\" data-id=\"9caff94\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-49dde70 elementor-widget elementor-widget-text-editor\" data-id=\"49dde70\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t <ul>\n                <li>Certification PMBIA Niveau 1 (obligatoire)<\/li>\n                <li>L'adh\u00e9sion \u00e0 PMBIA est non incluse dans le co\u00fbt du module.<\/li>\n                <li>2+ saisons d'exp\u00e9rience en enseignement recommand\u00e9, mais non obligatoire.<\/li>\n                <li>Lecture et exercice pr\u00e9paratoires \u00e0 compl\u00e9ter avant le cours (2-3 heures)<\/li>\n                <li>Confiance \u00e0 rouler \u00e0 vitesse sur un terrain technique et fluide de niveau interm\u00e9diaire \u00e0 avanc\u00e9<\/li>\n                <li>Secourisme en r\u00e9gion \u00e9loign\u00e9e fortement recommand\u00e9e<\/li>\n                <li>\u00c2ge minimum : 17 ans (en raison de la responsabilit\u00e9 l\u00e9gale envers les \u00e9l\u00e8ves)<\/li>\n            <\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-da6479c elementor-widget elementor-widget-n-accordion\" data-id=\"da6479c\" data-element_type=\"widget\" data-settings=\"{&quot;default_state&quot;:&quot;all_collapsed&quot;,&quot;max_items_expended&quot;:&quot;one&quot;,&quot;n_accordion_animation_duration&quot;:{&quot;unit&quot;:&quot;ms&quot;,&quot;size&quot;:400,&quot;sizes&quot;:[]}}\" data-widget_type=\"nested-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"e-n-accordion\" aria-label=\"Survol du Ride Guide\">\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-2290\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"1\" tabindex=\"0\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-2290\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Ce que vous apprendrez - Niveau 2 TECH <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><i aria-hidden=\"true\" class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t<span class='e-closed'><i aria-hidden=\"true\" class=\"fas fa-plus\"><\/i><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-2290\" class=\"elementor-element elementor-element-5f6ae19 e-con-full e-flex e-con e-child\" data-id=\"5f6ae19\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a217284 elementor-widget elementor-widget-text-editor\" data-id=\"a217284\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La certification d'instructeur PMBIA Niveau 2\/3 \u2013 TECH forme les instructeurs \u00e0 enseigner des habilet\u00e9s interm\u00e9diaires et avanc\u00e9s sur des sentiers naturels. Le cours met l'accent sur le perfectionnement des comp\u00e9tences en virages naturels \u00e0 plat et sur-\u00e9lev\u00e9s, sur les mont\u00e9es et descentes techniques sur pistes bleus, noirs et certaines double noirs.<\/p>\n<ul>\n<li>Apprenez \u00e0 enseigner les techniques en terrain naturel, en mont\u00e9e et en descente, sur des sentiers techniques allant du terrain cross-country engag\u00e9 vers les circuits d'enduro.<\/li>\n<li>Raffinez vos habilet\u00e9s en mont\u00e9e technique, en descente technique, en virages, cassures roul\u00e9s (roll-down) et en manoeuvres techniques; bunny-hops, stoppies, wheelies et pivots de la roue avant.<\/li>\n<li><span style=\"background-color: var( --e-global-color-c1e5146 ); text-align: var(--text-align); letter-spacing: 0px;\">Am\u00e9liorez votre gestion des risques, votre encadrement et vos habilet\u00e9s relationnelles \u00e0 plus haute vitesse.<\/span><\/li>\n<li>Utilisez les mod\u00e8les et m\u00e9thodologies PMBIA pour structurer des cours efficaces.<\/li>\n<li>Recevez du mentorat, pratiquez l\u2019enseignement et obtenez des retours quotidiens d\u2019un formateur PMBIA.<\/li>\n<\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-2291\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"2\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-2291\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> \u00c0 qui s\u2019adresse ce cours <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><i aria-hidden=\"true\" class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t<span class='e-closed'><i aria-hidden=\"true\" class=\"fas fa-plus\"><\/i><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-2291\" class=\"elementor-element elementor-element-f4a9741 e-con-full e-flex e-con e-child\" data-id=\"f4a9741\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-91ee278 elementor-widget elementor-widget-text-editor\" data-id=\"91ee278\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Con\u00e7u pour les instructeurs certifi\u00e9s PMBIA souhaitant enseigner aux riders interm\u00e9diaires \u00e0 avanc\u00e9s sur des terrains techniques naturels.<\/p>\n<ul>\n<li>Id\u00e9ale pour les \u00e9coles de v\u00e9lo, les clubs et les services de coaching.<\/li>\n<li>Sur des sentiers bleus, noirs et double noirs naturels.<\/li>\n<li>Des le\u00e7ons ax\u00e9s sur les virages naturels \u00e0 plats et sur\u00e9lev\u00e9s, sur les mont\u00e9es techniques et les descentes techniques, incluant les cassures roul\u00e9es, le pompage en terrain naturel.<\/li>\n<li>G\u00e9n\u00e9ralement offert dans les sites de pratique offrant une grande vari\u00e9t\u00e9 de terrain technique.&nbsp;&nbsp;<\/li><li><b>Les sites de pratiques avec remont\u00e9es m\u00e9caniques offrent en bonus plus de temps pass\u00e9 en descente technique et aident \u00e0 all\u00e9ger la fatigue physique.<\/b><\/li>\n<li>Dans des sites situ\u00e9s \u00e0 moins de 2 heures des soins m\u00e9dicaux d\u2019urgence<\/li>\n<\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-2292\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"3\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-2292\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Pourquoi prendre ce cours? <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><i aria-hidden=\"true\" class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t<span class='e-closed'><i aria-hidden=\"true\" class=\"fas fa-plus\"><\/i><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-2292\" class=\"elementor-element elementor-element-3f8c70b e-con-full e-flex e-con e-child\" data-id=\"3f8c70b\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-925d8e7 elementor-widget elementor-widget-text-editor\" data-id=\"925d8e7\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t <ul>\n                <li>Obtenez votre certification pour enseigner sur des terrains avanc\u00e9s et ma\u00eetriser des techniques avanc\u00e9es.<\/li>\n                <li>Acqu\u00e9rez une exp\u00e9rience concr\u00e8te du coaching dans des situations r\u00e9elles.<\/li>\n                <li>Apprenez des m\u00e9thodes d\u2019enseignement structur\u00e9es et bas\u00e9es sur les habilet\u00e9s avec des formateurs exp\u00e9riment\u00e9s de la PMBIA.<\/li>\n                <li>Am\u00e9liorez votre gestion des risques et votre planification de cours pour le pilotage \u00e0 haute vitesse.<\/li>\n                <li>Faites progresser votre carri\u00e8re en enseignement du v\u00e9lo avec une certification reconnue dans l\u2019industrie.<\/li>\n            <\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-2293\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"4\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-2293\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Pr\u00e9-requis <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><i aria-hidden=\"true\" class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t<span class='e-closed'><i aria-hidden=\"true\" class=\"fas fa-plus\"><\/i><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-2293\" class=\"elementor-element elementor-element-96b7867 e-con-full e-flex e-con e-child\" data-id=\"96b7867\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8a9c8d1 elementor-widget elementor-widget-text-editor\" data-id=\"8a9c8d1\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t <ul>\n                <li>Certification PMBIA Niveau 1 (obligatoire)<\/li>\n                <li>L'adh\u00e9sion \u00e0 PMBIA est non incluse dans le co\u00fbt du module.<\/li>\n                <li>2+ saisons d'exp\u00e9rience en enseignement recommand\u00e9, mais non obligatoire.<\/li>\n                <li>Lecture et exercice pr\u00e9paratoires \u00e0 compl\u00e9ter avant le cours (2-3 heures)<\/li>\n                <li>Confiance \u00e0 rouler \u00e0 vitesse sur un terrain technique et fluide de niveau interm\u00e9diaire \u00e0 avanc\u00e9<\/li>\n                <li>Secourisme en r\u00e9gion \u00e9loign\u00e9e fortement recommand\u00e9e<\/li>\n                <li>\u00c2ge minimum : 17 ans (en raison de la responsabilit\u00e9 l\u00e9gale envers les \u00e9l\u00e8ves)<\/li>\n            <\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6e273c1 e-flex e-con-boxed e-con e-parent\" data-id=\"6e273c1\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2a881f9 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"2a881f9\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Je suis un instructeur certifi\u00e9 Niveau II<br>Quelle est la prochaine \u00e9tape?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ffbcf7f elementor-widget elementor-widget-text-editor\" data-id=\"ffbcf7f\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Le syst\u00e8me \u00e0 quatre niveaux du PMBIA offre de nombreuses opportunit\u00e9s de d\u00e9veloppement professionnel. Devenir instructeur Niveau 3 vous positionne comme un entra\u00eeneur de haute performance.&nbsp;<\/p>\n<p>Pour d\u00e9velopper un ensemble de comp\u00e9tences complet, un instructeur visant le statut de Niveau III est encourag\u00e9 \u00e0 compl\u00e9ter l\u2019ensemble du parcours Niveau II, en AIR et en TECH. Le candidat doit d\u00e9montrer un haut niveau de ma\u00eetrise, en obtenant au moins \u00ab Autonome \u00bb (4 sur 5) dans tous les aspects du riding et du coaching, tout en servant de mod\u00e8le et de mentor pour les autres candidats Niveau II.<br><br>La derni\u00e8re \u00e9tape est de compl\u00e9ter le module Kids, qui permet aux instructeurs Niveau 3 d\u2019acqu\u00e9rir tous les outils n\u00e9cessaires pour exceller en tant qu\u2019entra\u00eeneurs de haute performance.<\/p>\n<p>Le cours de Niveau 4 est un programme intensif de cinq jours destin\u00e9 aux entra\u00eeneurs experts qui visent le plus haut niveau de certification de l'industrie. Il offre une formation avanc\u00e9e couvrant toutes les situations qu'un coach peut rencontrer, n\u00e9cessitant une ma\u00eetrise approfondie du pilotage, de l'enseignement et des diff\u00e9rentes approches p\u00e9dagogiques.&nbsp;<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a41bf0a e-flex e-con-boxed e-con e-parent\" data-id=\"a41bf0a\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1e8a999 elementor-widget elementor-widget-video\" data-id=\"1e8a999\" data-element_type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/youtu.be\\\/AkCke8o4dco&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;play_on_mobile&quot;:&quot;yes&quot;,&quot;loop&quot;:&quot;yes&quot;,&quot;show_image_overlay&quot;:&quot;yes&quot;,&quot;image_overlay&quot;:{&quot;url&quot;:&quot;https:\\\/\\\/pmbiaquebec.ca\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/PMBIA-Quebec.jpg&quot;,&quot;id&quot;:30736,&quot;size&quot;:&quot;&quot;,&quot;alt&quot;:&quot;&quot;,&quot;source&quot;:&quot;library&quot;},&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t\t\t<div class=\"elementor-custom-embed-image-overlay\" style=\"background-image: url(https:\/\/pmbiaquebec.ca\/wp-content\/uploads\/2025\/03\/PMBIA-Quebec.jpg);\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-custom-embed-play\" role=\"button\" aria-label=\"Lire la vid\u00e9o\" tabindex=\"0\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-play\"><\/i>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ba08e1b e-flex e-con-boxed e-con e-parent\" data-id=\"ba08e1b\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-b96b5e0 e-grid e-con-full e-con e-child\" data-id=\"b96b5e0\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-23ded07 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"23ded07\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">MISSION DE PMBIA<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e150f0e elementor-widget elementor-widget-text-editor\" data-id=\"e150f0e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tL'objectif de PMBIA est d'inspirer l'excellence dans l'enseignement, l'encadrement et l'entra\u00eenement en v\u00e9lo de montagne. Gr\u00e2ce \u00e0 un contenu et une formation reconnus par l'industrie, PMBIA accompagne les instructeurs, guides et entra\u00eeneurs \u00e0 offrir des standards de formation coh\u00e9rents et professionnels, \u00e0 l'\u00e9chelle mondiale.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7bcb3e1 e-flex e-con-boxed e-con e-parent\" data-id=\"7bcb3e1\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b9e317e elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"b9e317e\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Avec PMBIA Qu\u00e9bec, les instructeurs profitent d'une formation de qualit\u00e9, alliant des standards internationaux et une forte implication locale.\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b331b94 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"b331b94\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Men\u00e9 par une \u00e9quipe de <strong>formateurs d\u00e9di\u00e9s, bas\u00e9s au Qu\u00e9bec<\/strong>, garantissant une expertise locale et un encadrement personnalis\u00e9.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Disponible sp\u00e9cifiquement en <strong>Fran\u00e7ais et en Anglais (selon la r\u00e9gion)<\/strong>, cette formation reconnue \u00e0 l'international devient ainsi accessible \u00e0 tous.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Soutenue par des <strong>guides de r\u00e9f\u00e9rence et des livrets traduits en fran\u00e7ais par l'Association V\u00e9lo Qu\u00e9bec, <\/strong>garantissant clart\u00e9 et facilit\u00e9 d'apprentissage.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Fier d\u2019\u00eatre dirig\u00e9 par un <strong>organisme \u00e0 but non lucratif local<\/strong>, nous t\u00e9moignons ainsi de notre engagement \u00e0 am\u00e9liorer la qualit\u00e9 de l'encadrement dans la province de Qu\u00e9bec.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-fdcb562 e-con-full e-flex e-con e-parent\" data-id=\"fdcb562\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-e1c7ce6 e-flex e-con-boxed e-con e-child\" data-id=\"e1c7ce6\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-e8fc924 e-con-full e-flex e-con e-child\" data-id=\"e8fc924\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2e9aa66 elementor-widget elementor-widget-heading\" data-id=\"2e9aa66\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Pourquoi devenir membre?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e122e04 elementor-widget elementor-widget-text-editor\" data-id=\"e122e04\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>L'adh\u00e9sion \u00e0 la PMBIA soutient sa croissance, le d\u00e9veloppement de ses programmes et son r\u00f4le dans l\u2019industrie. La PMBIA rend l\u2019apprentissage plus s\u00fbr et accessible, encourageant plus de gens \u00e0 rouler ! Les membres b\u00e9n\u00e9ficient aussi de rabais exclusifs avec nos partenaires.<\/p>  \n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2690cc7 e-grid e-con-boxed e-con e-parent\" data-id=\"2690cc7\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-ca97b20 e-con-full e-flex e-con e-child\" data-id=\"ca97b20\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-a3f0729 e-con-full e-flex e-con e-child\" data-id=\"a3f0729\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8e42bbc elementor-widget elementor-widget-heading\" data-id=\"8e42bbc\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">ADH\u00c9SION ANNUELLE \u00c0 PMBIA<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a3c6171 elementor-widget elementor-widget-text-editor\" data-id=\"a3c6171\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>L'adh\u00e9sion annuelle \u00e0 PMBIA permet aux membres de profiter de nombreux avantages, notamment l'acc\u00e8s \u00e0 tout le mat\u00e9riel p\u00e9dagogique fran\u00e7ais et anglais ainsi qu'aux offres professionnelles de l'industrie.<\/p>\n<p>Les frais d'adh\u00e9sion contribuent \u00e9galement \u00e0 soutenir  PMBIA. Ces frais sont directement affect\u00e9s \u00e0 :<\/p>\n<ul>\n<li>Administration de l'association<\/li>\n<li>D\u00e9velopper des nouveaux contenus de le\u00e7ons<\/li>\n<li>Mise \u00e0 jour du site web et am\u00e9lioration des processus<\/li>\n<li>Cr\u00e9er des liens avec les acteurs influents de l'industrie<\/li>\n<\/ul>\n<p>Les cotisations des membres sont essentielles pour faire vivre PMBIA. Si vous aimez l'association, soutenez-l\u00e0 <strong>devenant membre<\/strong> ou en <strong>payant votre cotisation annuelle!<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-fab7b1a e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"fab7b1a\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeInRight&quot;}\">\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3b87dc81 e-flex e-con-boxed e-con e-parent\" data-id=\"3b87dc81\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-5e299748 e-con-full e-flex e-con e-child\" data-id=\"5e299748\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-12e11936 e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"12e11936\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeInRight&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-1d9dc7bd e-con-full e-flex e-con e-child\" data-id=\"1d9dc7bd\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-238637ec e-con-full e-flex e-con e-child\" data-id=\"238637ec\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a516b7a elementor-widget elementor-widget-heading\" data-id=\"a516b7a\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">PMBIA est une association de certification reconnue mondialement<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-eeda859 elementor-widget elementor-widget-text-editor\" data-id=\"eeda859\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tPMBIA est la r\u00e9f\u00e9rence mondiale en certification des instructeurs de v\u00e9lo de montagne, garantissant un coaching de qualit\u00e9 sup\u00e9rieure et efficace pour tous les niveaux de riders.\n<br><br>\nReconnu au Qu\u00e9bec par V\u00e9lo Qu\u00e9bec, l'AEQ et l'ASSQ, il r\u00e9pond aux normes de l'industrie tout en s'adaptant aux besoins locaux.\n<br><br>\nAvec des ressources en fran\u00e7ais, une mission \u00e0 but non lucratif et un esprit d'\u00e9quipe, PMBIA forme de meilleurs coachs et des riders plus forts \u00e0 travers le monde.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-68a2c52f e-flex e-con-boxed e-con e-parent\" data-id=\"68a2c52f\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-58e56333 e-con-full e-flex e-con e-child\" data-id=\"58e56333\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-78311950 elementor-widget elementor-widget-heading\" data-id=\"78311950\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">6 raisons de choisir PMBIA versus les autres programmes de certifications<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-798eb99e elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"798eb99e\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1148d7a9 e-con-full e-flex e-con e-child\" data-id=\"1148d7a9\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-43e42f94 elementor-widget elementor-widget-heading\" data-id=\"43e42f94\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Bas\u00e9 au Qu\u00e9bec, pour les besoins du Qu\u00e9bec!<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-435b9911 elementor-widget elementor-widget-text-editor\" data-id=\"435b9911\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tD\u00e9velopp\u00e9 avec une expertise locale, PMBIA comprend les besoins uniques de la sc\u00e8ne qu\u00e9b\u00e9coise du v\u00e9lo de montagne\u2014son terrain, sa culture et sa communaut\u00e9.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2999705 elementor-widget elementor-widget-heading\" data-id=\"2999705\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Certification reconnue au Qu\u00e9bec par VQ, AEQ et l'ASSQ<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c0c3559 elementor-widget elementor-widget-text-editor\" data-id=\"c0c3559\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tApprouv\u00e9e par V\u00e9lo Qu\u00e9bec, l'AEQ et l'ASSQ, PMBIA garantit une certification conforme aux normes de l'industrie et aux r\u00e9glementations provinciales.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3430438 elementor-widget elementor-widget-heading\" data-id=\"3430438\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Au service des besoins sp\u00e9cifiques de votre club ou \u00e9cole de v\u00e9lo<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6c8171e elementor-widget elementor-widget-text-editor\" data-id=\"6c8171e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tNos programmes s\u2019adaptent \u00e0 votre r\u00e9alit\u00e9, que vous donniez des cours, guidiez des sorties ou formiez la prochaine g\u00e9n\u00e9ration de riders.\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2e5eacc elementor-widget elementor-widget-heading\" data-id=\"2e5eacc\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Fi\u00e8rement un organisme sans but lucratif<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e0b3153 elementor-widget elementor-widget-text-editor\" data-id=\"e0b3153\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tPort\u00e9 par la passion, non le profit\u2014chaque dollar est r\u00e9investi pour am\u00e9liorer l'encadrement, d\u00e9velopper de nouvelles ressources et soutenir la communaut\u00e9 du v\u00e9lo de montagne.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b64447b elementor-widget elementor-widget-heading\" data-id=\"b64447b\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Documents traduit en Fran\u00e7ais, service \u00e0 la client\u00e8le en Fran\u00e7ais!<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cc7e98b elementor-widget elementor-widget-text-editor\" data-id=\"cc7e98b\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tDes manuels au soutien, tout est disponible en fran\u00e7ais, garantissant accessibilit\u00e9 et simplicit\u00e9 pour les instructeurs et organisations \u00e0 travers le Qu\u00e9bec.\n\n\n\n\n\n\n\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cd18fab elementor-widget elementor-widget-heading\" data-id=\"cd18fab\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">D\u00e9veloppement professionnel et confr\u00e9rie d'entraide<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4a47f33 elementor-widget elementor-widget-text-editor\" data-id=\"4a47f33\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tAu-del\u00e0 des comp\u00e9tences techniques, PMBIA d\u00e9veloppe le leadership, la communication et la collaboration, aidant les instructeurs \u00e0 \u00e9voluer sur et en dehors du v\u00e9lo.\n\n\n\n\n\n\n\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>IMPROVE YOUR RIDING SHARE YOUR PASSION BECOME A MTB COACH TODAY! GLOBAL INDUSTRY CERTIFICATION STANDARD Level II and III Certification program Elevate your coaching! Elevate your coaching with the AIR and TECH certification training! These 4-day courses sharpen your riding and teaching beyond Level 1. The TECH Certification program refines all our trail skills such [&hellip;]<\/p>","protected":false},"author":1,"featured_media":28372,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>PMBIA Qu\u00e9bec \/ PMBIA QUEBEC - NIVEAU 2 CERTIFICATION CERTIFICATION VELO DE MONTAGNE<\/title>\n<meta name=\"description\" content=\"PMBIA - Certification de guides et instructeurs. Niveau 2 (4 jours) - Formation et Certification avanc\u00e9e d&#039;entra\u00eeneurs en v\u00e9lo de montagne\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/pmbiaquebec.ca\/fr\/pmbia-quebec-niveau-2-certification\/\" \/>\n<meta property=\"og:locale\" content=\"fr_CA\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"PMBIA Qu\u00e9bec \/ PMBIA QUEBEC - NIVEAU 2 CERTIFICATION CERTIFICATION VELO DE MONTAGNE\" \/>\n<meta property=\"og:description\" content=\"PMBIA - Certification de guides et instructeurs. Niveau 2 (4 jours) - Formation et Certification avanc\u00e9e d&#039;entra\u00eeneurs en v\u00e9lo de montagne\" \/>\n<meta property=\"og:url\" content=\"https:\/\/pmbiaquebec.ca\/fr\/pmbia-quebec-niveau-2-certification\/\" \/>\n<meta property=\"og:site_name\" content=\"PMBIA Qu\u00e9bec\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Bikeskillsca-2194275320683514\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-08-29T12:15:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/pmbiaquebec.ca\/wp-content\/uploads\/2025\/01\/Screenshot-2025-01-27-at-12.26.44.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"1136\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Estimation du temps de lecture\" \/>\n\t<meta name=\"twitter:data1\" content=\"10 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/pmbiaquebec.ca\/fr\/pmbia-quebec-niveau-2-certification\/\",\"url\":\"https:\/\/pmbiaquebec.ca\/fr\/pmbia-quebec-niveau-2-certification\/\",\"name\":\"PMBIA Qu\u00e9bec \/ PMBIA QUEBEC - NIVEAU 2 CERTIFICATION CERTIFICATION VELO DE MONTAGNE\",\"isPartOf\":{\"@id\":\"https:\/\/pmbiaquebec.ca\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/pmbiaquebec.ca\/fr\/pmbia-quebec-niveau-2-certification\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/pmbiaquebec.ca\/fr\/pmbia-quebec-niveau-2-certification\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/pmbiaquebec.ca\/wp-content\/uploads\/2025\/01\/Screenshot-2025-01-27-at-12.26.44.jpg\",\"datePublished\":\"2025-03-15T12:44:59+00:00\",\"dateModified\":\"2026-08-29T12:15:42+00:00\",\"description\":\"PMBIA - Certification de guides et instructeurs. Niveau 2 (4 jours) - Formation et Certification avanc\u00e9e d'entra\u00eeneurs en v\u00e9lo de montagne\",\"breadcrumb\":{\"@id\":\"https:\/\/pmbiaquebec.ca\/fr\/pmbia-quebec-niveau-2-certification\/#breadcrumb\"},\"inLanguage\":\"fr-CA\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/pmbiaquebec.ca\/fr\/pmbia-quebec-niveau-2-certification\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\/\/pmbiaquebec.ca\/fr\/pmbia-quebec-niveau-2-certification\/#primaryimage\",\"url\":\"https:\/\/pmbiaquebec.ca\/wp-content\/uploads\/2025\/01\/Screenshot-2025-01-27-at-12.26.44.jpg\",\"contentUrl\":\"https:\/\/pmbiaquebec.ca\/wp-content\/uploads\/2025\/01\/Screenshot-2025-01-27-at-12.26.44.jpg\",\"width\":1200,\"height\":1136},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/pmbiaquebec.ca\/fr\/pmbia-quebec-niveau-2-certification\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/pmbiaquebec.ca\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"PMBIA QUEBEC &#8211; NIVEAU 2 CERTIFICATION\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/pmbiaquebec.ca\/en\/#website\",\"url\":\"https:\/\/pmbiaquebec.ca\/en\/\",\"name\":\"PMBIA Qu\u00e9bec\",\"description\":\"PMBIA Qu\u00e9bec - Formation de guide et entraineurs\",\"publisher\":{\"@id\":\"https:\/\/pmbiaquebec.ca\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/pmbiaquebec.ca\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-CA\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/pmbiaquebec.ca\/en\/#organization\",\"name\":\"PMBIA Qu\u00e9bec\",\"url\":\"https:\/\/pmbiaquebec.ca\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\/\/pmbiaquebec.ca\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/pmbiaquebec.ca\/wp-content\/uploads\/2021\/01\/PMBIA-LOGO-FAVICON.png\",\"contentUrl\":\"https:\/\/pmbiaquebec.ca\/wp-content\/uploads\/2021\/01\/PMBIA-LOGO-FAVICON.png\",\"width\":350,\"height\":203,\"caption\":\"PMBIA Qu\u00e9bec\"},\"image\":{\"@id\":\"https:\/\/pmbiaquebec.ca\/en\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/Bikeskillsca-2194275320683514\/\",\"https:\/\/www.instagram.com\/pmbiaquebec.ca\/?hl=fr\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"PMBIA Qu\u00e9bec \/ PMBIA QUEBEC - NIVEAU 2 CERTIFICATION CERTIFICATION VELO DE MONTAGNE","description":"PMBIA - Certification de guides et instructeurs. Niveau 2 (4 jours) - Formation et Certification avanc\u00e9e d'entra\u00eeneurs en v\u00e9lo de montagne","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/pmbiaquebec.ca\/fr\/pmbia-quebec-niveau-2-certification\/","og_locale":"fr_CA","og_type":"article","og_title":"PMBIA Qu\u00e9bec \/ PMBIA QUEBEC - NIVEAU 2 CERTIFICATION CERTIFICATION VELO DE MONTAGNE","og_description":"PMBIA - Certification de guides et instructeurs. Niveau 2 (4 jours) - Formation et Certification avanc\u00e9e d'entra\u00eeneurs en v\u00e9lo de montagne","og_url":"https:\/\/pmbiaquebec.ca\/fr\/pmbia-quebec-niveau-2-certification\/","og_site_name":"PMBIA Qu\u00e9bec","article_publisher":"https:\/\/www.facebook.com\/Bikeskillsca-2194275320683514\/","article_modified_time":"2026-08-29T12:15:42+00:00","og_image":[{"width":1200,"height":1136,"url":"https:\/\/pmbiaquebec.ca\/wp-content\/uploads\/2025\/01\/Screenshot-2025-01-27-at-12.26.44.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Estimation du temps de lecture":"10 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/pmbiaquebec.ca\/fr\/pmbia-quebec-niveau-2-certification\/","url":"https:\/\/pmbiaquebec.ca\/fr\/pmbia-quebec-niveau-2-certification\/","name":"PMBIA Qu\u00e9bec \/ PMBIA QUEBEC - NIVEAU 2 CERTIFICATION CERTIFICATION VELO DE MONTAGNE","isPartOf":{"@id":"https:\/\/pmbiaquebec.ca\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/pmbiaquebec.ca\/fr\/pmbia-quebec-niveau-2-certification\/#primaryimage"},"image":{"@id":"https:\/\/pmbiaquebec.ca\/fr\/pmbia-quebec-niveau-2-certification\/#primaryimage"},"thumbnailUrl":"https:\/\/pmbiaquebec.ca\/wp-content\/uploads\/2025\/01\/Screenshot-2025-01-27-at-12.26.44.jpg","datePublished":"2025-03-15T12:44:59+00:00","dateModified":"2026-08-29T12:15:42+00:00","description":"PMBIA - Certification de guides et instructeurs. Niveau 2 (4 jours) - Formation et Certification avanc\u00e9e d'entra\u00eeneurs en v\u00e9lo de montagne","breadcrumb":{"@id":"https:\/\/pmbiaquebec.ca\/fr\/pmbia-quebec-niveau-2-certification\/#breadcrumb"},"inLanguage":"fr-CA","potentialAction":[{"@type":"ReadAction","target":["https:\/\/pmbiaquebec.ca\/fr\/pmbia-quebec-niveau-2-certification\/"]}]},{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/pmbiaquebec.ca\/fr\/pmbia-quebec-niveau-2-certification\/#primaryimage","url":"https:\/\/pmbiaquebec.ca\/wp-content\/uploads\/2025\/01\/Screenshot-2025-01-27-at-12.26.44.jpg","contentUrl":"https:\/\/pmbiaquebec.ca\/wp-content\/uploads\/2025\/01\/Screenshot-2025-01-27-at-12.26.44.jpg","width":1200,"height":1136},{"@type":"BreadcrumbList","@id":"https:\/\/pmbiaquebec.ca\/fr\/pmbia-quebec-niveau-2-certification\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/pmbiaquebec.ca\/en\/"},{"@type":"ListItem","position":2,"name":"PMBIA QUEBEC &#8211; NIVEAU 2 CERTIFICATION"}]},{"@type":"WebSite","@id":"https:\/\/pmbiaquebec.ca\/en\/#website","url":"https:\/\/pmbiaquebec.ca\/en\/","name":"PMBIA Qu\u00e9bec","description":"PMBIA Qu\u00e9bec - Formation de guide et entraineurs","publisher":{"@id":"https:\/\/pmbiaquebec.ca\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/pmbiaquebec.ca\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-CA"},{"@type":"Organization","@id":"https:\/\/pmbiaquebec.ca\/en\/#organization","name":"PMBIA Qu\u00e9bec","url":"https:\/\/pmbiaquebec.ca\/en\/","logo":{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/pmbiaquebec.ca\/en\/#\/schema\/logo\/image\/","url":"https:\/\/pmbiaquebec.ca\/wp-content\/uploads\/2021\/01\/PMBIA-LOGO-FAVICON.png","contentUrl":"https:\/\/pmbiaquebec.ca\/wp-content\/uploads\/2021\/01\/PMBIA-LOGO-FAVICON.png","width":350,"height":203,"caption":"PMBIA Qu\u00e9bec"},"image":{"@id":"https:\/\/pmbiaquebec.ca\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Bikeskillsca-2194275320683514\/","https:\/\/www.instagram.com\/pmbiaquebec.ca\/?hl=fr"]}]}},"_links":{"self":[{"href":"https:\/\/pmbiaquebec.ca\/fr\/wp-json\/wp\/v2\/pages\/31526"}],"collection":[{"href":"https:\/\/pmbiaquebec.ca\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/pmbiaquebec.ca\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/pmbiaquebec.ca\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/pmbiaquebec.ca\/fr\/wp-json\/wp\/v2\/comments?post=31526"}],"version-history":[{"count":151,"href":"https:\/\/pmbiaquebec.ca\/fr\/wp-json\/wp\/v2\/pages\/31526\/revisions"}],"predecessor-version":[{"id":33338,"href":"https:\/\/pmbiaquebec.ca\/fr\/wp-json\/wp\/v2\/pages\/31526\/revisions\/33338"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pmbiaquebec.ca\/fr\/wp-json\/wp\/v2\/media\/28372"}],"wp:attachment":[{"href":"https:\/\/pmbiaquebec.ca\/fr\/wp-json\/wp\/v2\/media?parent=31526"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}